{"id":111,"count":1,"description":"","link":"https:\/\/anabolex.com\/blog\/category\/sarms\/","name":"SARMS","slug":"sarms","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SARMS Archives - Anabolex Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anabolex.com\/blog\/category\/sarms\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SARMS Archives - Anabolex Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anabolex.com\/blog\/category\/sarms\/\" \/>\n<meta property=\"og:site_name\" content=\"Anabolex Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/category\\\/sarms\\\/\",\"url\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/category\\\/sarms\\\/\",\"name\":\"SARMS Archives - Anabolex Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/category\\\/sarms\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/category\\\/sarms\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SARMS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/\",\"name\":\"Anabolex Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/#organization\",\"name\":\"Anabolex Blog\",\"url\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-all-white.png\",\"contentUrl\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-all-white.png\",\"width\":300,\"height\":79,\"caption\":\"Anabolex Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SARMS Archives - Anabolex Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anabolex.com\/blog\/category\/sarms\/","og_locale":"en_US","og_type":"article","og_title":"SARMS Archives - Anabolex Blog","og_url":"https:\/\/anabolex.com\/blog\/category\/sarms\/","og_site_name":"Anabolex Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/anabolex.com\/blog\/category\/sarms\/","url":"https:\/\/anabolex.com\/blog\/category\/sarms\/","name":"SARMS Archives - Anabolex Blog","isPartOf":{"@id":"https:\/\/anabolex.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/anabolex.com\/blog\/category\/sarms\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/anabolex.com\/blog\/category\/sarms\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/anabolex.com\/blog\/"},{"@type":"ListItem","position":2,"name":"SARMS"}]},{"@type":"WebSite","@id":"https:\/\/anabolex.com\/blog\/#website","url":"https:\/\/anabolex.com\/blog\/","name":"Anabolex Blog","description":"","publisher":{"@id":"https:\/\/anabolex.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anabolex.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/anabolex.com\/blog\/#organization","name":"Anabolex Blog","url":"https:\/\/anabolex.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anabolex.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/anabolex.com\/blog\/wp-content\/uploads\/2023\/03\/logo-all-white.png","contentUrl":"https:\/\/anabolex.com\/blog\/wp-content\/uploads\/2023\/03\/logo-all-white.png","width":300,"height":79,"caption":"Anabolex Blog"},"image":{"@id":"https:\/\/anabolex.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/anabolex.com\/blog\/wp-json\/wp\/v2\/categories\/111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anabolex.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/anabolex.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/anabolex.com\/blog\/wp-json\/wp\/v2\/posts?categories=111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}