{"id":5,"name":"Ronald C Wilson","url":"","description":"Dr. Ronald C. Wilson is a highly experienced and accomplished African-American exercise science practitioner, with NASM, ISSA, ACSM, NCSF personal trainer certifications.\r\n\r\nDr. Wilson earned his doctorate in exercise science from the prestigious Brown university, but he now chooses to help bodybuilders achieve their goals.\r\n\r\nAs a certified trainer, Dr. Wilson works with fitness models, bodybuilders, figure competitors, and normal guys jumping on TRT. His main diet push is for low carbs, vegan diets for long term health.","link":"https:\/\/anabolex.com\/blog\/author\/ronaldcwilson\/","slug":"ronaldcwilson","avatar_urls":{"24":"https:\/\/anabolex.com\/blog\/wp-content\/uploads\/2023\/05\/ronald-c-wilson_avatar-24x24.jpg","48":"https:\/\/anabolex.com\/blog\/wp-content\/uploads\/2023\/05\/ronald-c-wilson_avatar-48x48.jpg","96":"https:\/\/anabolex.com\/blog\/wp-content\/uploads\/2023\/05\/ronald-c-wilson_avatar-96x96.jpg"},"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ronald C Wilson, Author at Anabolex Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anabolex.com\/blog\/author\/ronaldcwilson\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Ronald C Wilson, Author at Anabolex Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anabolex.com\/blog\/author\/ronaldcwilson\/\" \/>\n<meta property=\"og:site_name\" content=\"Anabolex Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/anabolex.com\/blog\/wp-content\/uploads\/2023\/05\/ronald-c-wilson_avatar-200x328.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/author\\\/ronaldcwilson\\\/\",\"url\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/author\\\/ronaldcwilson\\\/\",\"name\":\"Ronald C Wilson, Author at Anabolex Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/author\\\/ronaldcwilson\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/anabolex.com\\\/blog\\\/author\\\/ronaldcwilson\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/author\\\/ronaldcwilson\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archives for Ronald C Wilson\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/\",\"name\":\"Anabolex Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/#organization\",\"name\":\"Anabolex Blog\",\"url\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-all-white.png\",\"contentUrl\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-all-white.png\",\"width\":300,\"height\":79,\"caption\":\"Anabolex Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/#\\\/schema\\\/person\\\/057daa76e661e1042f217be892123af8\",\"name\":\"Ronald C Wilson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/ronald-c-wilson_avatar-96x96.jpg\",\"url\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/ronald-c-wilson_avatar-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/ronald-c-wilson_avatar-96x96.jpg\",\"caption\":\"Ronald C Wilson\"},\"description\":\"Dr. Ronald C. Wilson is a highly experienced and accomplished African-American exercise science practitioner, with NASM, ISSA, ACSM, NCSF personal trainer certifications. Dr. Wilson earned his doctorate in exercise science from the prestigious Brown university, but he now chooses to help bodybuilders achieve their goals. As a certified trainer, Dr. Wilson works with fitness models, bodybuilders, figure competitors, and normal guys jumping on TRT. His main diet push is for low carbs, vegan diets for long term health.\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/anabolex.com\\\/blog\\\/author\\\/ronaldcwilson\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ronald C Wilson, Author at Anabolex Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anabolex.com\/blog\/author\/ronaldcwilson\/","og_locale":"en_US","og_type":"profile","og_title":"Ronald C Wilson, Author at Anabolex Blog","og_url":"https:\/\/anabolex.com\/blog\/author\/ronaldcwilson\/","og_site_name":"Anabolex Blog","og_image":[{"url":"https:\/\/anabolex.com\/blog\/wp-content\/uploads\/2023\/05\/ronald-c-wilson_avatar-200x328.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/anabolex.com\/blog\/author\/ronaldcwilson\/","url":"https:\/\/anabolex.com\/blog\/author\/ronaldcwilson\/","name":"Ronald C Wilson, Author at Anabolex Blog","isPartOf":{"@id":"https:\/\/anabolex.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/anabolex.com\/blog\/author\/ronaldcwilson\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anabolex.com\/blog\/author\/ronaldcwilson\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/anabolex.com\/blog\/author\/ronaldcwilson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/anabolex.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Archives for Ronald C Wilson"}]},{"@type":"WebSite","@id":"https:\/\/anabolex.com\/blog\/#website","url":"https:\/\/anabolex.com\/blog\/","name":"Anabolex Blog","description":"","publisher":{"@id":"https:\/\/anabolex.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anabolex.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/anabolex.com\/blog\/#organization","name":"Anabolex Blog","url":"https:\/\/anabolex.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anabolex.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/anabolex.com\/blog\/wp-content\/uploads\/2023\/03\/logo-all-white.png","contentUrl":"https:\/\/anabolex.com\/blog\/wp-content\/uploads\/2023\/03\/logo-all-white.png","width":300,"height":79,"caption":"Anabolex Blog"},"image":{"@id":"https:\/\/anabolex.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/anabolex.com\/blog\/#\/schema\/person\/057daa76e661e1042f217be892123af8","name":"Ronald C Wilson","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/anabolex.com\/blog\/wp-content\/uploads\/2023\/05\/ronald-c-wilson_avatar-96x96.jpg","url":"https:\/\/anabolex.com\/blog\/wp-content\/uploads\/2023\/05\/ronald-c-wilson_avatar-96x96.jpg","contentUrl":"https:\/\/anabolex.com\/blog\/wp-content\/uploads\/2023\/05\/ronald-c-wilson_avatar-96x96.jpg","caption":"Ronald C Wilson"},"description":"Dr. Ronald C. Wilson is a highly experienced and accomplished African-American exercise science practitioner, with NASM, ISSA, ACSM, NCSF personal trainer certifications. Dr. Wilson earned his doctorate in exercise science from the prestigious Brown university, but he now chooses to help bodybuilders achieve their goals. As a certified trainer, Dr. Wilson works with fitness models, bodybuilders, figure competitors, and normal guys jumping on TRT. His main diet push is for low carbs, vegan diets for long term health.","mainEntityOfPage":{"@id":"https:\/\/anabolex.com\/blog\/author\/ronaldcwilson\/"}}]}},"_links":{"self":[{"href":"https:\/\/anabolex.com\/blog\/wp-json\/wp\/v2\/users\/5","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anabolex.com\/blog\/wp-json\/wp\/v2\/users"}]}}